{"id":8,"count":2,"description":"","link":"https:\/\/berghotel-hohegeiss.com\/en\/category\/todo","name":"Todo","slug":"todo","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todo Archives - Berghotel Hohegeiss<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo Archives - Berghotel Hohegeiss\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berghotel-hohegeiss.com\/en\/category\/todo\/\" \/>\n<meta property=\"og:site_name\" content=\"Berghotel Hohegeiss\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/category\\\/todo\",\"url\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/category\\\/todo\",\"name\":\"Todo Archives - Berghotel Hohegeiss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/category\\\/todo#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/category\\\/todo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/#website\",\"url\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/\",\"name\":\"Berghotel Hohegeiss\",\"description\":\"hotel pension hohegeiss hohegei\u00df\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo Archives - Berghotel Hohegeiss","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Todo Archives - Berghotel Hohegeiss","og_url":"https:\/\/berghotel-hohegeiss.com\/en\/category\/todo\/","og_site_name":"Berghotel Hohegeiss","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/berghotel-hohegeiss.com\/category\/todo","url":"https:\/\/berghotel-hohegeiss.com\/category\/todo","name":"Todo Archives - Berghotel Hohegeiss","isPartOf":{"@id":"https:\/\/berghotel-hohegeiss.com\/#website"},"breadcrumb":{"@id":"https:\/\/berghotel-hohegeiss.com\/category\/todo#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/berghotel-hohegeiss.com\/category\/todo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/berghotel-hohegeiss.com\/"},{"@type":"ListItem","position":2,"name":"Todo"}]},{"@type":"WebSite","@id":"https:\/\/berghotel-hohegeiss.com\/#website","url":"https:\/\/berghotel-hohegeiss.com\/","name":"Berghotel Hohegeiss","description":"hotel pension hohegeiss hohegei\u00df","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berghotel-hohegeiss.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}