{"id":5749,"date":"2025-08-20T10:59:39","date_gmt":"2025-08-20T10:59:39","guid":{"rendered":"https:\/\/berghotel-hohegeiss.com\/?p=5749"},"modified":"2026-01-16T15:22:51","modified_gmt":"2026-01-16T15:22:51","slug":"standard-double-room","status":"publish","type":"page","link":"https:\/\/berghotel-hohegeiss.com\/en\/unsere-zimmer\/doppelzimmer-standard","title":{"rendered":"Double Room Standard"},"content":{"rendered":"\n<p>Modernes Doppelzimmer mit separatem Bad. Von Ihrem Zimmer aus haben Sie einen wundersch\u00f6nen Blick auf den Harz. <\/p>\n\n\n\n<p>Im Berghotel Hohegeiss stehen Ihnen insgesamt vier Doppelzimmer Standard zur Verf\u00fcgung \u2013 jede dieser Unterk\u00fcnfte ist individuell gestaltet und bietet gem\u00fctlichen Komfort.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zimmergr\u00f6\u00dfe 22-24 m<sup>2<\/sup><\/li>\n\n\n\n<li>Komfortabeles Doppelbett 180 x 200 cm<\/li>\n\n\n\n<li>Flachbildfernseher mit Satellitenprogrammen<\/li>\n\n\n\n<li>Kleiderschrank<\/li>\n\n\n\n<li>Rauch und Haustier frei<\/li>\n\n\n\n<li>Badezimmer in 2025 renoviert<\/li>\n<\/ul>\n\n\n\n<div class=\"room-availability\" data-room-code=\"p8VCa7VEHA0s\"><\/div>\n\n\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-5200\"><form id=\"wpforms-form-5200\" class=\"wpforms-validate wpforms-form\" data-formid=\"5200\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/5749\" data-token=\"defceba8a399dbf4c61d6b6e8f96f649\" data-token-time=\"1778702130\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-5200-field_4-container\" class=\"wpforms-field wpforms-field-text date-icon\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-5200-field_4\">Anreise datum<\/label><input type=\"text\" id=\"wpforms-5200-field_4\" class=\"wpforms-field-large\" name=\"wpforms[fields][4]\" value=\"13\/05\/2026\" placeholder=\"DD\/MM\/YYYY\" ><\/div>\t\t<div id=\"wpforms-5200-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-5200-field_1\" >datum Anreise datum<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-5200-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-5200-field_5-container\" class=\"wpforms-field wpforms-field-text date-icon departure-date\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-5200-field_5\">Abreise datum<\/label><input type=\"text\" id=\"wpforms-5200-field_5\" class=\"wpforms-field-large\" name=\"wpforms[fields][5]\" placeholder=\"DD\/MM\/YYYY\" ><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-5200-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-5200-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-5200-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"5200\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/pages\/5749\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-5200\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet\u00a0\u2026\" data-submit-text=\"Verf\u00fcgbarkeit pr\u00fcfen\" aria-live=\"assertive\" value=\"wpforms-submit\">Verf\u00fcgbarkeit pr\u00fcfen<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\n\n\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\/\/berghotel-hohegeiss.com\/en\/unsere-zimmer\/doppelzimmer-standard&quot;}' id='gallery-1' class='gallery galleryid-5749 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/en\/?attachment_id=5358'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\u00dcbersicht des Doppelzimmers Standard mit 180 x 200 cm Boxspringbett, zwei Sesseln und kleinem Tisch im Berghotel Hohegeiss\" aria-describedby=\"gallery-1-5358\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"5358\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/en\/?attachment_id=5358\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 16&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1738147170&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"berghotel hohegeiss doppelzimmer\" data-image-description=\"&lt;p&gt;Diese \u00dcbersicht des Doppelzimmers Standard im Berghotel Hohegeiss zeigt das zentrale 180 x 200 cm gro\u00dfe Boxspringbett sowie zwei gem\u00fctliche Sessel mit einem kleinen Tisch. Die freundliche Einrichtung und das durchdachte Raumkonzept bieten Komfort und Entspannung f\u00fcr zwei Personen.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Doppelzimmer Standard mit komfortablem Doppelbett und gem\u00fctlicher Sitzecke \u2013 Berghotel Hohegeiss&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-5358'>\n\t\t\t\tDoppelzimmer Standard mit komfortablem Doppelbett und gem\u00fctlicher Sitzecke \u2013 Berghotel Hohegeiss\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/en\/?attachment_id=5018'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Modernes Hotelbad mit bodengleicher Dusche, h\u00e4ngendem WC und Waschbecken mit beheiztem Spiegel \u2013 Renovierung 2025\" aria-describedby=\"gallery-1-5018\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"5018\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/en\/?attachment_id=5018\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken.jpeg\" data-orig-size=\"1536,2048\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 16&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1734359349&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;iPhone 16 back dual wide camera 2.22mm f\/2.2&quot;}\" data-image-title=\"Modernes Badezimmer \u2013 Renoviert 2025 \u2013 Berghotel Hohegeiss\" data-image-description=\"&lt;p&gt;Dieses Badezimmerbild wird f\u00fcr mehrere Zimmerkategorien des Berghotels Hohegeiss verwendet. Es zeigt die 2025 renovierte Ausstattung mit bodengleicher Dusche, wandh\u00e4ngendem WC und einem modernen Waschbecken samt beheiztem LED-Spiegel \u2013 funktional und stilvoll zugleich.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Modernes Badezimmer mit Komfortausstattung \u2013 g\u00fcltig f\u00fcr mehrere Zimmerkategorien im Berghotel Hohegeiss&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken-768x1024.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-5018'>\n\t\t\t\tModernes Badezimmer mit Komfortausstattung \u2013 g\u00fcltig f\u00fcr mehrere Zimmerkategorien im Berghotel Hohegeiss\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/en\/img_1833'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-standard-modern-renoviert-berghotel-hohegeiss-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Neu renoviertes Doppelzimmer Standard im Berghotel Hohegei\u00df mit komfortablem Doppelbett\" aria-describedby=\"gallery-1-6355\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-standard-modern-renoviert-berghotel-hohegeiss-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-standard-modern-renoviert-berghotel-hohegeiss-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"6355\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/en\/img_1833\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-standard-modern-renoviert-berghotel-hohegeiss-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 16&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1766498971&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;640&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Modernes Doppelzimmer\" data-image-description=\"&lt;p&gt;Modern und neu renoviertes Doppelzimmer Standard im Berghotel Hohegei\u00df mit komfortablem Doppelbett und zeitgem\u00e4\u00dfer Ausstattung. Ideal f\u00fcr einen erholsamen Aufenthalt im Harz.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Modern renoviertes Doppelzimmer Standard&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-standard-modern-renoviert-berghotel-hohegeiss-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-6355'>\n\t\t\t\tModern renoviertes Doppelzimmer Standard\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/en\/img_1825'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-modern-renoviert-2026-berghotel-hohegeiss-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Modern renoviertes Doppelzimmer im Berghotel Hohegei\u00df \u2013 frisch renoviert im Jahr 2026\" aria-describedby=\"gallery-1-6353\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-modern-renoviert-2026-berghotel-hohegeiss-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-modern-renoviert-2026-berghotel-hohegeiss-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"6353\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/en\/img_1825\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-modern-renoviert-2026-berghotel-hohegeiss-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 16&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1766494025&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;640&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Doppelzimmer Standard\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Neu gestaltetes Doppelzimmer 2026&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2026\/01\/doppelzimmer-modern-renoviert-2026-berghotel-hohegeiss-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-6353'>\n\t\t\t\tNeu gestaltetes Doppelzimmer 2026\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/en\/?attachment_id=4924'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Erstes Schlafzimmer im Familienzimmer mit 180 x 200 cm Doppelbett im Berghotel Hohegei\u00df\" aria-describedby=\"gallery-1-4924\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"4924\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/en\/?attachment_id=4924\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1736684695&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.54&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.0023094688221709&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Familienzimmer \u2013 Erstes Schlafzimmer mit Doppelbett \u2013 Berghotel Hohegei\u00df\" data-image-description=\"&lt;p&gt;Dieses Bild zeigt das erste Schlafzimmer des Familienzimmers im Berghotel Hohegei\u00df. Der helle Raum ist mit einem komfortablen 180 x 200 cm Doppelbett ausgestattet und ideal f\u00fcr Eltern oder Paare geeignet. Gro\u00dfe Fenster sorgen f\u00fcr viel Tageslicht und eine angenehme Atmosph\u00e4re.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Helles Schlafzimmer mit gro\u00dfem Doppelbett \u2013 Familienzimmer im Berghotel Hohegei\u00df&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-4924'>\n\t\t\t\tHelles Schlafzimmer mit gro\u00dfem Doppelbett \u2013 Familienzimmer im Berghotel Hohegei\u00df\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/en\/img_3373'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/IMG_3373-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1047\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/IMG_3373-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/IMG_3373-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"1047\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/en\/img_3373\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/IMG_3373-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1703598994&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.54&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"IMG_3373\" data-image-description=\"&lt;p&gt;Renovierte Badezimmer Doppelzimmer mit Terrasse&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Badezimmer&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/IMG_3373-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1047'>\n\t\t\t\tBadezimmer\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Modern double room with separate bathroom. <br \/>Max 2 persons<\/p>\n<p>From \u20ac 90 <br \/>incl. breakfast<\/p>","protected":false},"author":1,"featured_media":5358,"parent":791,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5749","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Doppelzimmer Standard - Berghotel Hohegeiss<\/title>\n<meta name=\"description\" content=\"Standard Doppelzimmer im Berghotel Hohegeiss mit 180 x 200 cm Boxspringbett, gem\u00fctlicher Sitzecke und renoviertem Badezimmer. Ideal f\u00fcr Paare oder Alleinreisende.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/berghotel-hohegeiss.com\/en\/our-rooms\/standard-double-room\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doppelzimmer Standard - Berghotel Hohegeiss\" \/>\n<meta property=\"og:description\" content=\"Standard Doppelzimmer im Berghotel Hohegeiss mit 180 x 200 cm Boxspringbett, gem\u00fctlicher Sitzecke und renoviertem Badezimmer. Ideal f\u00fcr Paare oder Alleinreisende.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berghotel-hohegeiss.com\/en\/our-rooms\/standard-double-room\/\" \/>\n<meta property=\"og:site_name\" content=\"Berghotel Hohegeiss\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Berghotel-Hohegeiss-101262279197312\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T15:22:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/doppelzimmer-standard\",\"url\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/doppelzimmer-standard\",\"name\":\"Doppelzimmer Standard - Berghotel Hohegeiss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/doppelzimmer-standard#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/doppelzimmer-standard#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-scaled.jpeg\",\"datePublished\":\"2025-08-20T10:59:39+00:00\",\"dateModified\":\"2026-01-16T15:22:51+00:00\",\"description\":\"Standard Doppelzimmer im Berghotel Hohegeiss mit 180 x 200 cm Boxspringbett, gem\u00fctlicher Sitzecke und renoviertem Badezimmer. Ideal f\u00fcr Paare oder Alleinreisende.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/doppelzimmer-standard#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/doppelzimmer-standard\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/doppelzimmer-standard#primaryimage\",\"url\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-scaled.jpeg\",\"width\":2560,\"height\":1920,\"caption\":\"Doppelzimmer Standard mit komfortablem Doppelbett und gem\u00fctlicher Sitzecke \u2013 Berghotel Hohegeiss\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/doppelzimmer-standard#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Zimmer\",\"item\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Doppelzimmer Standard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/#website\",\"url\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/\",\"name\":\"Berghotel Hohegeiss\",\"description\":\"hotel pension hohegeiss hohegei\u00df\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Standard double room - Berghotel Hohegeiss","description":"Standard double room in the Berghotel Hohegeiss with 180 x 200 cm box-spring bed, cosy sitting area and renovated bathroom. Ideal for couples or single travellers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/berghotel-hohegeiss.com\/en\/our-rooms\/standard-double-room\/","og_locale":"en_GB","og_type":"article","og_title":"Doppelzimmer Standard - Berghotel Hohegeiss","og_description":"Standard Doppelzimmer im Berghotel Hohegeiss mit 180 x 200 cm Boxspringbett, gem\u00fctlicher Sitzecke und renoviertem Badezimmer. Ideal f\u00fcr Paare oder Alleinreisende.","og_url":"https:\/\/berghotel-hohegeiss.com\/en\/our-rooms\/standard-double-room\/","og_site_name":"Berghotel Hohegeiss","article_publisher":"https:\/\/www.facebook.com\/Berghotel-Hohegeiss-101262279197312","article_modified_time":"2026-01-16T15:22:51+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-scaled.jpeg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/doppelzimmer-standard","url":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/doppelzimmer-standard","name":"Standard double room - Berghotel Hohegeiss","isPartOf":{"@id":"https:\/\/berghotel-hohegeiss.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/doppelzimmer-standard#primaryimage"},"image":{"@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/doppelzimmer-standard#primaryimage"},"thumbnailUrl":"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-scaled.jpeg","datePublished":"2025-08-20T10:59:39+00:00","dateModified":"2026-01-16T15:22:51+00:00","description":"Standard double room in the Berghotel Hohegeiss with 180 x 200 cm box-spring bed, cosy sitting area and renovated bathroom. Ideal for couples or single travellers.","breadcrumb":{"@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/doppelzimmer-standard#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/doppelzimmer-standard"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/doppelzimmer-standard#primaryimage","url":"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-scaled.jpeg","contentUrl":"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-doppelzimmer-standard-uebersicht-bett-sitzecke-scaled.jpeg","width":2560,"height":1920,"caption":"Doppelzimmer Standard mit komfortablem Doppelbett und gem\u00fctlicher Sitzecke \u2013 Berghotel Hohegeiss"},{"@type":"BreadcrumbList","@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/doppelzimmer-standard#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/berghotel-hohegeiss.com\/"},{"@type":"ListItem","position":2,"name":"Unsere Zimmer","item":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer"},{"@type":"ListItem","position":3,"name":"Doppelzimmer Standard"}]},{"@type":"WebSite","@id":"https:\/\/berghotel-hohegeiss.com\/#website","url":"https:\/\/berghotel-hohegeiss.com\/","name":"Berghotel Hohegeiss","description":"hotel pension hohegeiss hohegei\u00df","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berghotel-hohegeiss.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/pages\/5749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/comments?post=5749"}],"version-history":[{"count":4,"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/pages\/5749\/revisions"}],"predecessor-version":[{"id":6359,"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/pages\/5749\/revisions\/6359"}],"up":[{"embeddable":true,"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/pages\/791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/media\/5358"}],"wp:attachment":[{"href":"https:\/\/berghotel-hohegeiss.com\/en\/wp-json\/wp\/v2\/media?parent=5749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}