{"id":5751,"date":"2025-08-20T11:04:03","date_gmt":"2025-08-20T11:04:03","guid":{"rendered":"https:\/\/berghotel-hohegeiss.com\/?p=5751"},"modified":"2026-01-09T16:10:59","modified_gmt":"2026-01-09T16:10:59","slug":"familiekamer","status":"publish","type":"page","link":"https:\/\/berghotel-hohegeiss.com\/nl\/unsere-zimmer\/familienzimmer","title":{"rendered":"Familiekamer"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>Im Berghotel Hohegei\u00df steht Ihnen ein Familienzimmer zur Verf\u00fcgung, das aus zwei gro\u00dfz\u00fcgigen Schlafzimmern mit einem gemeinsamen Bad besteht. In einem der Schlafzimmer befindet sich eine Sitzecke mit einem Schlafsofa, das als zus\u00e4tzlicher Schlafplatz genutzt werden kann \u2013 somit bietet das Zimmer Platz f\u00fcr bis zu f\u00fcnf Personen.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zimmergr\u00f6\u00dfe 42 m<sup>2<\/sup><\/li>\n\n\n\n<li>2x Komfortabeles Doppelbett 180 x 200 cm<\/li>\n\n\n\n<li>1x Schlafsofa<\/li>\n\n\n\n<li>Flachbildfernseher mit Satellitenkan\u00e4len<\/li>\n\n\n\n<li>Kleiderschrank<\/li>\n\n\n\n<li>Rauch und Haustier frei<\/li>\n\n\n\n<li>Badezimmer in 2025 renoviert<\/li>\n<\/ul>\n\n\n\n<div class=\"room-availability\" data-room-code=\"oCl8ywgPMXFc\"><\/div>\n\n\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-5200\"><form id=\"wpforms-form-5200\" class=\"wpforms-validate wpforms-form\" data-formid=\"5200\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/nl\/wp-json\/wp\/v2\/pages\/5751\" data-token=\"4d077f90ca0558a5dfd8ed15ef864258\" data-token-time=\"1784150202\"><noscript class=\"wpforms-error-noscript\">Schakel JavaScript in je browser in om dit formulier in te vullen.<\/noscript><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-5200-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-5200-field_1\" >datum datum Abreise<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-5200-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-5200-field_4-container\" class=\"wpforms-field wpforms-field-text date-icon\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-5200-field_4\">Anreise datum<\/label><input type=\"text\" id=\"wpforms-5200-field_4\" class=\"wpforms-field-large\" name=\"wpforms[fields][4]\" value=\"15\/07\/2026\" placeholder=\"DD\/MM\/YYYY\" ><\/div><div id=\"wpforms-5200-field_5-container\" class=\"wpforms-field wpforms-field-text date-icon departure-date\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-5200-field_5\">Abreise datum<\/label><input type=\"text\" id=\"wpforms-5200-field_5\" class=\"wpforms-field-large\" name=\"wpforms[fields][5]\" placeholder=\"DD\/MM\/YYYY\" ><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-5200-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-5200-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-5200-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"5200\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/pages\/5751\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-5200\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet\u00a0\u2026\" data-submit-text=\"Verf\u00fcgbarkeit pr\u00fcfen\" aria-live=\"assertive\" value=\"wpforms-submit\">Verf\u00fcgbarkeit pr\u00fcfen<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\n\n\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\/\/berghotel-hohegeiss.com\/nl\/unsere-zimmer\/familienzimmer&quot;}' id='gallery-1' class='gallery galleryid-5751 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4924'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Erstes Schlafzimmer im Familienzimmer mit 180 x 200 cm Doppelbett im Berghotel Hohegei\u00df\" aria-describedby=\"gallery-1-4924\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"4924\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4924\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1736684695&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.54&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.0023094688221709&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Familienzimmer \u2013 Erstes Schlafzimmer mit Doppelbett \u2013 Berghotel Hohegei\u00df\" data-image-description=\"&lt;p&gt;Dieses Bild zeigt das erste Schlafzimmer des Familienzimmers im Berghotel Hohegei\u00df. Der helle Raum ist mit einem komfortablen 180 x 200 cm Doppelbett ausgestattet und ideal f\u00fcr Eltern oder Paare geeignet. Gro\u00dfe Fenster sorgen f\u00fcr viel Tageslicht und eine angenehme Atmosph\u00e4re.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Helles Schlafzimmer mit gro\u00dfem Doppelbett \u2013 Familienzimmer im Berghotel Hohegei\u00df&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-licht-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-4924'>\n\t\t\t\tHelles Schlafzimmer mit gro\u00dfem Doppelbett \u2013 Familienzimmer im Berghotel Hohegei\u00df\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4927'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-doppelbett-schlafcouch-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Zweites Schlafzimmer im Familienzimmer mit 180 x 200 cm Doppelbett und Schlafcouch f\u00fcr eine dritte Person im Berghotel Hohegei\u00df\" aria-describedby=\"gallery-1-4927\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-doppelbett-schlafcouch-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-doppelbett-schlafcouch-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"4927\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4927\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-doppelbett-schlafcouch-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1736683813&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.54&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Familienzimmer \u2013 Zweites Schlafzimmer mit Doppelbett und Schlafcouch \u2013 Berghotel Hohegei\u00df\" data-image-description=\"&lt;p&gt;Das zweite Schlafzimmer im Familienzimmer des Berghotels Hohegei\u00df bietet flexible Schlafm\u00f6glichkeiten f\u00fcr Familien: ein komfortables 180 x 200 cm Doppelbett sowie eine Schlafcouch, die sich ideal f\u00fcr eine dritte Person oder ein Kind eignet. Die Einrichtung ist freundlich, hell und funktional \u2013 perfekt f\u00fcr gemeinsame Erholung.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Zweites Schlafzimmer mit gro\u00dfem Doppelbett und zus\u00e4tzlicher Schlafcouch \u2013 ideal f\u00fcr Familien mit drei Personen&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-doppelbett-schlafcouch-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-4927'>\n\t\t\t\tZweites Schlafzimmer mit gro\u00dfem Doppelbett und zus\u00e4tzlicher Schlafcouch \u2013 ideal f\u00fcr Familien mit drei Personen\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=5018'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Modernes Hotelbad mit bodengleicher Dusche, h\u00e4ngendem WC und Waschbecken mit beheiztem Spiegel \u2013 Renovierung 2025\" aria-describedby=\"gallery-1-5018\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"5018\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=5018\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken.jpeg\" data-orig-size=\"1536,2048\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 16&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1734359349&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;iPhone 16 back dual wide camera 2.22mm f\/2.2&quot;}\" data-image-title=\"Modernes Badezimmer \u2013 Renoviert 2025 \u2013 Berghotel Hohegeiss\" data-image-description=\"&lt;p&gt;Dieses Badezimmerbild wird f\u00fcr mehrere Zimmerkategorien des Berghotels Hohegeiss verwendet. Es zeigt die 2025 renovierte Ausstattung mit bodengleicher Dusche, wandh\u00e4ngendem WC und einem modernen Waschbecken samt beheiztem LED-Spiegel \u2013 funktional und stilvoll zugleich.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Modernes Badezimmer mit Komfortausstattung \u2013 g\u00fcltig f\u00fcr mehrere Zimmerkategorien im Berghotel Hohegeiss&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-badezimmer-2025-renoviert-dusche-waschbecken-768x1024.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-5018'>\n\t\t\t\tModernes Badezimmer mit Komfortausstattung \u2013 g\u00fcltig f\u00fcr mehrere Zimmerkategorien im Berghotel Hohegeiss\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4922'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-ausblick-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Schlafzimmer im Familienzimmer mit Ausblick auf den Harz im Berghotel Hohegei\u00df\" aria-describedby=\"gallery-1-4922\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-ausblick-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-ausblick-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"4922\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4922\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-ausblick-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1736685005&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.54&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.0016260162601626&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Familienzimmer \u2013 Schlafzimmer mit Ausblick auf den Harz \u2013 Berghotel Hohegei\u00df\" data-image-description=\"&lt;p&gt;Diese Aufnahme zeigt das erste Schlafzimmer des Familienzimmers im Berghotel Hohegei\u00df mit einem herrlichen Blick auf den Harz. Durch die gro\u00dfen Fenster f\u00e4llt viel Tageslicht in den Raum, was die freundliche Atmosph\u00e4re zus\u00e4tzlich unterstreicht.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Ausblick aus dem Schlafzimmer des Familienzimmers auf den Harz \u2013 Berghotel Hohegei\u00df&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-ausblick-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-4922'>\n\t\t\t\tAusblick aus dem Schlafzimmer des Familienzimmers auf den Harz \u2013 Berghotel Hohegei\u00df\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4928'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-willkommensgruss-wasserkarte-orchidee-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Willkommensgru\u00df im Familienzimmer mit Flasche Wasser, zwei Gl\u00e4sern, Gru\u00dfkarte, Orchidee und chinesischer Winkekatze im Berghotel Hohegei\u00df\" aria-describedby=\"gallery-1-4928\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-willkommensgruss-wasserkarte-orchidee-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-willkommensgruss-wasserkarte-orchidee-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"4928\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4928\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-willkommensgruss-wasserkarte-orchidee-scaled.jpeg\" data-orig-size=\"1768,2560\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1736688074&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.1&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Familienzimmer \u2013 Willkommensgru\u00df mit Wasser, Karte und Orchidee \u2013 Berghotel Hohegei\u00df\" data-image-description=\"&lt;p&gt;Ein liebevoll arrangierter Willkommensgru\u00df erwartet die G\u00e4ste im Familienzimmer des Berghotels Hohegei\u00df: eine Flasche Wasser mit zwei Gl\u00e4sern, eine pers\u00f6nliche Gru\u00dfkarte, eine zarte Schmetterlingsorchidee und eine kleine chinesische Winkekatze sorgen f\u00fcr einen herzlichen Empfang und ein wohnliches Ambiente.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Liebevoller Willkommensgru\u00df im Familienzimmer \u2013 mit Wasser, Gru\u00dfkarte und kleiner Dekoration&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-willkommensgruss-wasserkarte-orchidee-707x1024.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-4928'>\n\t\t\t\tLiebevoller Willkommensgru\u00df im Familienzimmer \u2013 mit Wasser, Gru\u00dfkarte und kleiner Dekoration\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4925'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-schlafcouch-sessel-schrank-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Zweites Schlafzimmer im Familienzimmer mit Schlafcouch, gem\u00fctlichem Sessel und ger\u00e4umigem Kleiderschrank im Berghotel Hohegei\u00df\" aria-describedby=\"gallery-1-4925\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-schlafcouch-sessel-schrank-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-schlafcouch-sessel-schrank-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"4925\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4925\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-schlafcouch-sessel-schrank-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1736684129&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.54&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.0079365079365079&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Familienzimmer \u2013 Zweites Schlafzimmer mit Schlafcouch, Sessel und Schrank \u2013 Berghotel Hohegei\u00df\" data-image-description=\"&lt;p&gt;Diese Aufnahme zeigt das zweite Schlafzimmer des Familienzimmers im Berghotel Hohegei\u00df. Neben dem Doppelbett bietet der Raum eine bequeme Schlafcouch, einen gem\u00fctlichen Lesesessel und einen gro\u00dfen Kleiderschrank zur Aufbewahrung. Die Ausstattung eignet sich ideal f\u00fcr Familien mit Kindern oder drei Erwachsene.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Schlafcouch, Sessel und viel Stauraum \u2013 zweites Schlafzimmer im Familienzimmer des Berghotels Hohegei\u00df&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-schlafcouch-sessel-schrank-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-4925'>\n\t\t\t\tSchlafcouch, Sessel und viel Stauraum \u2013 zweites Schlafzimmer im Familienzimmer des Berghotels Hohegei\u00df\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4923'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-sitzecke-tv-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Schlafzimmer im Familienzimmer mit Sitzecke, Tisch und Flachbildfernseher im Berghotel Hohegei\u00df\" aria-describedby=\"gallery-1-4923\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-sitzecke-tv-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-sitzecke-tv-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"4923\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4923\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-sitzecke-tv-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1736684804&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.54&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.0013003901170351&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Familienzimmer \u2013 Schlafzimmer mit Sitzecke und TV \u2013 Berghotel Hohegei\u00df\" data-image-description=\"&lt;p&gt;Diese Aufnahme zeigt das erste Schlafzimmer des Familienzimmers im Berghotel Hohegei\u00df mit zus\u00e4tzlicher Ausstattung: eine gem\u00fctliche Sitzecke mit zwei Sesseln und einem kleinen Tisch sowie ein moderner Flachbildfernseher sorgen f\u00fcr Wohnkomfort wie zu Hause. Ideal f\u00fcr Familien, die auch im Urlaub entspannen m\u00f6chten.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Erstes Schlafzimmer mit gem\u00fctlicher Sitzecke und Flachbild-TV \u2013 Familienzimmer im Berghotel Hohegei\u00df&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-1-sitzecke-tv-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-4923'>\n\t\t\t\tErstes Schlafzimmer mit gem\u00fctlicher Sitzecke und Flachbild-TV \u2013 Familienzimmer im Berghotel Hohegei\u00df\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4926'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-ausblick-harz-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Zweites Schlafzimmer im Familienzimmer mit Doppelbett und Ausblick auf den Harz im Berghotel Hohegei\u00df\" aria-describedby=\"gallery-1-4926\" srcset=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-ausblick-harz-150x150.jpeg 150w, https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-ausblick-harz-480x480.jpeg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"4926\" data-permalink=\"https:\/\/berghotel-hohegeiss.com\/nl\/?attachment_id=4926\" data-orig-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-ausblick-harz-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1736684035&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.54&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0079365079365079&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;lens&quot;:&quot;&quot;}\" data-image-title=\"Familienzimmer \u2013 Zweites Schlafzimmer mit Ausblick auf den Harz \u2013 Berghotel Hohegei\u00df\" data-image-description=\"&lt;p&gt;Diese Aufnahme zeigt das zweite Schlafzimmer des Familienzimmers im Berghotel Hohegei\u00df. Vom komfortablen Doppelbett aus genie\u00dft man einen direkten Blick auf die Harzer Landschaft. Die gro\u00dfen Fenster sorgen f\u00fcr viel Licht und eine offene, entspannte Atmosph\u00e4re \u2013 perfekt f\u00fcr einen erholsamen Aufenthalt.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Zweites Schlafzimmer mit herrlichem Ausblick auf den Harz \u2013 Familienzimmer im Berghotel Hohegei\u00df&lt;\/p&gt;\n\" data-large-file=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/berghotel-hohegeiss-familienzimmer-schlafzimmer-2-ausblick-harz-1024x768.jpeg\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-4926'>\n\t\t\t\tZweites Schlafzimmer mit herrlichem Ausblick auf den Harz \u2013 Familienzimmer im Berghotel Hohegei\u00df\n\t\t\t\t<\/dd><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>De familiekamer bestaat uit twee grote slaapkamers met een gedeelde badkamer.<br \/>\nMax 5 personen<br \/>\nVanaf \u20ac 180<br \/>incl. ontbijt<\/p>","protected":false},"author":1,"featured_media":923,"parent":791,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5751","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Familienzimmer - Berghotel Hohegeiss<\/title>\n<meta name=\"description\" content=\"Familienzimmer mit zwei Schlafzimmern im Berghotel Hohegeiss. Ideal f\u00fcr Familien bis 5 Personen \u2013 mit Schlafcouch, Harzblick und viel Komfort.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/berghotel-hohegeiss.com\/nl\/de-kamers\/familiekamer\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Familienzimmer - Berghotel Hohegeiss\" \/>\n<meta property=\"og:description\" content=\"Familienzimmer mit zwei Schlafzimmern im Berghotel Hohegeiss. Ideal f\u00fcr Familien bis 5 Personen \u2013 mit Schlafcouch, Harzblick und viel Komfort.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berghotel-hohegeiss.com\/nl\/de-kamers\/familiekamer\/\" \/>\n<meta property=\"og:site_name\" content=\"Berghotel Hohegeiss\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Berghotel-Hohegeiss-101262279197312\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-09T16:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/Berghotel-Hohegeiss-Update-2023-50.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/familienzimmer\",\"url\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/familienzimmer\",\"name\":\"Familienzimmer - Berghotel Hohegeiss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/familienzimmer#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/familienzimmer#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Berghotel-Hohegeiss-Update-2023-50.jpg\",\"datePublished\":\"2025-08-20T11:04:03+00:00\",\"dateModified\":\"2026-01-09T16:10:59+00:00\",\"description\":\"Familienzimmer mit zwei Schlafzimmern im Berghotel Hohegeiss. Ideal f\u00fcr Familien bis 5 Personen \u2013 mit Schlafcouch, Harzblick und viel Komfort.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/familienzimmer#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/familienzimmer\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/familienzimmer#primaryimage\",\"url\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Berghotel-Hohegeiss-Update-2023-50.jpg\",\"contentUrl\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Berghotel-Hohegeiss-Update-2023-50.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\\\/familienzimmer#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Zimmer\",\"item\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/unsere-zimmer\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Familienzimmer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/#website\",\"url\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/\",\"name\":\"Berghotel Hohegeiss\",\"description\":\"hotel pension hohegeiss hohegei\u00df\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/berghotel-hohegeiss.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Familiekamer - Berghotel Hohegeiss","description":"Familiekamer met twee slaapkamers in Berghotel Hohegeiss. Ideaal voor gezinnen tot 5 personen - met slaapbank, uitzicht op het Harzgebergte en veel comfort.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/berghotel-hohegeiss.com\/nl\/de-kamers\/familiekamer\/","og_locale":"nl_NL","og_type":"article","og_title":"Familienzimmer - Berghotel Hohegeiss","og_description":"Familienzimmer mit zwei Schlafzimmern im Berghotel Hohegeiss. Ideal f\u00fcr Familien bis 5 Personen \u2013 mit Schlafcouch, Harzblick und viel Komfort.","og_url":"https:\/\/berghotel-hohegeiss.com\/nl\/de-kamers\/familiekamer\/","og_site_name":"Berghotel Hohegeiss","article_publisher":"https:\/\/www.facebook.com\/Berghotel-Hohegeiss-101262279197312","article_modified_time":"2026-01-09T16:10:59+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/Berghotel-Hohegeiss-Update-2023-50.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/familienzimmer","url":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/familienzimmer","name":"Familiekamer - Berghotel Hohegeiss","isPartOf":{"@id":"https:\/\/berghotel-hohegeiss.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/familienzimmer#primaryimage"},"image":{"@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/familienzimmer#primaryimage"},"thumbnailUrl":"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/Berghotel-Hohegeiss-Update-2023-50.jpg","datePublished":"2025-08-20T11:04:03+00:00","dateModified":"2026-01-09T16:10:59+00:00","description":"Familiekamer met twee slaapkamers in Berghotel Hohegeiss. Ideaal voor gezinnen tot 5 personen - met slaapbank, uitzicht op het Harzgebergte en veel comfort.","breadcrumb":{"@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/familienzimmer#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/familienzimmer"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/familienzimmer#primaryimage","url":"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/Berghotel-Hohegeiss-Update-2023-50.jpg","contentUrl":"https:\/\/berghotel-hohegeiss.com\/wp-content\/uploads\/2023\/12\/Berghotel-Hohegeiss-Update-2023-50.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer\/familienzimmer#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/berghotel-hohegeiss.com\/"},{"@type":"ListItem","position":2,"name":"Unsere Zimmer","item":"https:\/\/berghotel-hohegeiss.com\/unsere-zimmer"},{"@type":"ListItem","position":3,"name":"Familienzimmer"}]},{"@type":"WebSite","@id":"https:\/\/berghotel-hohegeiss.com\/#website","url":"https:\/\/berghotel-hohegeiss.com\/","name":"Berghotel Hohegeiss","description":"hotel pension hohegeiss hohegei\u00df","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berghotel-hohegeiss.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/pages\/5751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/comments?post=5751"}],"version-history":[{"count":3,"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/pages\/5751\/revisions"}],"predecessor-version":[{"id":6290,"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/pages\/5751\/revisions\/6290"}],"up":[{"embeddable":true,"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/pages\/791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/media\/923"}],"wp:attachment":[{"href":"https:\/\/berghotel-hohegeiss.com\/nl\/wp-json\/wp\/v2\/media?parent=5751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}